{"id":1724,"date":"2012-05-21T02:16:46","date_gmt":"2012-05-21T04:16:46","guid":{"rendered":"http:\/\/www.encontraitaquera.com.br\/noticias\/?p=1724"},"modified":"2019-04-12T18:50:19","modified_gmt":"2019-04-12T20:50:19","slug":"oficina-do-cat-itaquera-ensina-a-avaliar-habilidades-e-descobrir-potencialidades-profissionais","status":"publish","type":"post","link":"https:\/\/www.encontraitaquera.com.br\/sobre\/oficina-do-cat-itaquera-ensina-a-avaliar-habilidades-e-descobrir-potencialidades-profissionais\/","title":{"rendered":"Oficina do CAT Itaquera ensina a avaliar habilidades e descobrir potencialidades profissionais"},"content":{"rendered":"<div class=\"f6a401da1b960306e8d5ff784b0b5528\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Na pr\u00f3xima quarta-feira (23\/5), \u00e0s 9h, o Centro de Apoio ao Trabalho (CAT), da Secretaria Municipal de Desenvolvimento Econ\u00f4mico e do Trabalho (Semdet), realiza oficina gratuita do Programa Orienta\u00e7\u00e3o para o Trabalho. O tema da pr\u00f3xima semana \u00e9\u00a0<em>Habilidades<\/em>, que pretende auxiliar as pessoas a reservarem um momento para se avaliar e perceber habilidades que desconhecia.<\/p>\n<p>Um bom exemplo de habilidades que muitas vezes passam despercebidas s\u00e3o as atividades de uma dona de casa na manuten\u00e7\u00e3o e administra\u00e7\u00e3o do lar que precisa planejar as compras, gastos da semana e as tarefas do lar. Desta maneira,\u00a0 a dona de casa tem uma s\u00e9rie de habilidades, que podem ser muito bem aproveitadas, quando ingressar no mercado de trabalho. Durante a oficina no CAT ser\u00e1 poss\u00edvel n\u00e3o s\u00f3 fazer essas observa\u00e7\u00f5es, como tamb\u00e9m apreender t\u00e9cnicas para demonstr\u00e1-las na hora de concorrer a uma oportunidade de trabalho.<\/p>\n<p>O Programa Orienta\u00e7\u00e3o para o Trabalho tem como principal objetivo contribuir para melhorar e aperfei\u00e7oar o perfil profissional dos usu\u00e1rios do servi\u00e7o do CAT. A cada semana, as oficinas abordam um tema diferente, que est\u00e3o entre as principais d\u00favidas que as pessoas t\u00eam na hora de procurar um trabalho. Para participar \u00e9 necess\u00e1rio ter 16 anos completo, apresentar Carteira de Trabalho, RG, CPF e n\u00famero do PIS numa das unidades: Itaquera, S\u00e3o Mateus I, S\u00e3o Miguel Paulista, Santana, Luz, Jabaquara, Interlagos e Lapa I, al\u00e9m da Feira do Trabalho.<\/p>\n<p><strong>Servi\u00e7o:<\/strong><\/p>\n<p><strong>ZONA CENTRAL<\/strong><\/p>\n<p>CAT Luz<br \/>\nAv. Prestes Maia, 913 \/ 919<br \/>\nSegunda a sexta-feira, das 7h \u00e0s 18h<\/p>\n<p><strong>ZONA LESTE<br \/>\n<\/strong><\/p>\n<p><strong>CAT Itaquera<\/strong><br \/>\n<strong> Rua Greg\u00f3rio Ramalho, 12<\/strong><br \/>\n<strong> Segunda a sexta-feira, das 7h \u00e0s 18h<\/strong><\/p>\n<p>CAT Penha<br \/>\nRua Candapu\u00ed, 492 (dentro da\u00a0Subprefeitura da Penha)<br \/>\nSegunda a sexta-feira, das 8h \u00e0s 17h<\/p>\n<p>CAT S\u00e3o Mateus I<br \/>\nAv. Mateo Bei, 1.641<br \/>\nSegunda a sexta-feira, das 7h \u00e0s 18h<\/p>\n<p>CAT S\u00e3o Miguel Paulista<br \/>\nAv. Imperador, 1900, Pr\u00f3ximo ao terminal A. E Carvalho<br \/>\nSegunda a sexta-feira, das 8h \u00e0s 17h<\/p>\n<p><strong>ZONA NORTE<\/strong><\/p>\n<p>CAT Santana<br \/>\nRua Volunt\u00e1rios da P\u00e1tria, 1.553<br \/>\nSegunda a sexta-feira, das 7h \u00e0s 18h<\/p>\n<p><strong>ZONA OESTE<br \/>\n<\/strong><\/p>\n<p>CAT Lapa I<br \/>\nRua Monteiro de Melo, 342<br \/>\nSegunda a sexta-feira, das 7h \u00e0s 18h<\/p>\n<p><strong>ZONA SUL<\/strong><strong>\u00a0DE S\u00c3O PAULO<\/strong><strong><br \/>\n<\/strong><br \/>\nCAT Interlagos<br \/>\nAv. Interlagos, 6.122<br \/>\nSegunda a sexta-feira, das 7h \u00e0s 18h<\/p>\n<p>CAT Jabaquara<br \/>\nAv. Eng. Armando de Arruda Pereira, 2.314<br \/>\nSegunda a sexta-feira, das 8h \u00e0s 17h<\/p>\n<p><em>Fonte: Prefeitura de S. Paulo<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Na pr\u00f3xima quarta-feira (23\/5), \u00e0s 9h, o Centro de Apoio ao Trabalho (CAT), da Secretaria Municipal de Desenvolvimento Econ\u00f4mico e do Trabalho (Semdet), realiza oficina gratuita do Programa Orienta\u00e7\u00e3o para o Trabalho. O tema da pr\u00f3xima semana \u00e9\u00a0Habilidades, que pretende auxiliar as pessoas a reservarem um momento para se avaliar e perceber habilidades que desconhecia. Um bom exemplo de habilidades que muitas vezes passam despercebidas s\u00e3o as atividades de uma dona de casa na manuten\u00e7\u00e3o e administra\u00e7\u00e3o do lar que precisa planejar as compras, gastos da semana e as tarefas do lar. Desta maneira,\u00a0 a dona de casa tem uma <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1724","post","type-post","status-publish","format-standard","hentry","category-noticias-itaquera"],"_links":{"self":[{"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=1724"}],"version-history":[{"count":1,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1724\/revisions"}],"predecessor-version":[{"id":10418,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1724\/revisions\/10418"}],"wp:attachment":[{"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=1724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=1724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=1724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}