{"id":467,"date":"2011-05-12T15:19:10","date_gmt":"2011-05-12T17:19:10","guid":{"rendered":"http:\/\/www.encontraitaquera.com.br\/noticias\/?p=467"},"modified":"2019-04-12T18:54:20","modified_gmt":"2019-04-12T20:54:20","slug":"sub-itaquera-inicia-plano-de-acao-de-combate-a-incendio","status":"publish","type":"post","link":"https:\/\/www.encontraitaquera.com.br\/sobre\/sub-itaquera-inicia-plano-de-acao-de-combate-a-incendio\/","title":{"rendered":"Sub Itaquera inicia plano de a\u00e7\u00e3o de combate a inc\u00eandio"},"content":{"rendered":"<div class=\"f6a401da1b960306e8d5ff784b0b5528\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A Prefeitura de S\u00e3o Paulo criou o programa de preven\u00e7\u00e3o e combate a  inc\u00eandios em \u00e1reas consideradas de risco na cidade. O PREVIN foi criado  ap\u00f3s um mapeamento de 50 pontos realizado pelo Corpo de Bombeiros. O  trabalho feito numa comunidade do Jardim Aeroporto, na Zona Sul, servir\u00e1  como modelo. Pelo cronograma, o programa ser\u00e1 implantado nos 50 pontos  priorit\u00e1rios at\u00e9 o final de 2012.<\/p>\n<p>Caber\u00e3o as subprefeituras a tarefa de  articular com os diversos parceiros locais: representantes das  comunidades; Corpo de Bombeiros; Sabesp; AES Eletropaulo, a  implementa\u00e7\u00e3o do plano de prev\u00ea entre outras a\u00e7\u00f5es: alargamento de ruas,  retirada de &#8220;gatos&#8221; de energia el\u00e9trica, instala\u00e7\u00e3o de extintores e  hidrantes e a cria\u00e7\u00e3o de brigadas de combate a inc\u00eandios. Tamb\u00e9m ser\u00e3o  adotadas medidas para evitar a propaga\u00e7\u00e3o do fogo, como o afastamento de  edifica\u00e7\u00f5es e a cria\u00e7\u00e3o de rotas de fugas.<\/p>\n<p>Em conson\u00e2ncia com o programa, a Subprefeitura de Itaquera realizou  uma reuni\u00e3o explicativa sobre o PREVIN, com a participa\u00e7\u00e3o do  subprefeito; o coordenador de Defesa Civil da Sub Itaquera, Am\u00e9rico  Kikuta; e representantes da Sehab (Secretaria Municipal de Habita\u00e7\u00e3o);  GCM \u2013 Guarda Civil Metropolitana; Guarda Ambiental; e diretoria regional  de Educa\u00e7\u00e3o de guia Itaquera, que atuar\u00e1 na divulga\u00e7\u00e3o de panfletos  explicativos aos alunos da rede municipal.<\/p>\n<p>Entre os assuntos discutidos, o papel dos zeladores comunit\u00e1rios, que  ficar\u00e3o com a responsabilidade de coordenar a brigada de inc\u00eandio  formada por moradores que ser\u00e3o treinados pela Prefeitura, AES  Eletropaulo e os Bombeiros que dar\u00e3o palestras e cartilhas sobre  preven\u00e7\u00e3o de inc\u00eandios.<\/p>\n<p>O subprefeito abriu a reuni\u00e3o falando da import\u00e2ncia do PREVIN para  Itaquera e do momento que considera prop\u00edcio para dar in\u00edcio \u00e0s a\u00e7\u00f5es.<\/p>\n<p>\u201cTemos em Itaquera 53 assentamentos prec\u00e1rios, mas duas comunidades, em  especial nos causam preocupa\u00e7\u00e3o pela grande quantidade de casas de  madeira, Zorrilho e Maria Luiza Americano. Por isso, escolhemos essas  duas para darmos in\u00edcio ao programa na regi\u00e3o. E o momento \u00e9 oportuno  porque estamos saindo do per\u00edodo de chuva e entrando na estiagem, \u00e9poca  que costuma surgir focos de inc\u00eandio\u201d, disse.<\/p>\n<p>O coordenador de Defesa Civil da Subprefeitura de Itaquera, Am\u00e9rico  Kikuta, detalhou algumas a\u00e7\u00f5es que ser\u00e3o realizadas pelo PREVIN e falou  sobre a sistematiza\u00e7\u00e3o do programa. \u201c\u00c9 uma a\u00e7\u00e3o integrada, que envolve  diversas \u00e1reas da Prefeitura e do Estado. A Eletropaulo vai entrar  porque a maior causa de inc\u00eandios em favelas \u00e9 o famoso \u201cgato\u201d (liga\u00e7\u00e3o  clandestina de eletricidade). Pretendemos acabar com isso e regular os  pontos de energia.<\/p>\n<p>A Sa\u00fade, com o PSF (Programa Sa\u00fade da Fam\u00edlia) que  vai at\u00e9 a casa das pessoas, poder\u00e1 ajudar passando tamb\u00e9m orienta\u00e7\u00f5es  sobre preven\u00e7\u00e3o de risco de inc\u00eandio e a secretaria das Subprefeituras  que far\u00e1 cartilhas informativas explicando os cuidados com os manejos do  botij\u00e3o de g\u00e1s, velas e benjamim, liga\u00e7\u00f5es clandestinas de energia,  etc. Com a supervis\u00e3o do Corpo de Bombeiros, que colocar\u00e1 os extintores,  a Sabesp ajudar\u00e1 na quest\u00e3o dos hidrantes\u201d.<\/p>\n<p><em>Fonte: Prefeitura de S. Paulo<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de S\u00e3o Paulo criou o programa de preven\u00e7\u00e3o e combate a inc\u00eandios em \u00e1reas consideradas de risco na cidade. O PREVIN foi criado ap\u00f3s um mapeamento de 50 pontos realizado pelo Corpo de Bombeiros. O trabalho feito numa comunidade do Jardim Aeroporto, na Zona Sul, servir\u00e1 como modelo. Pelo cronograma, o programa ser\u00e1 implantado nos 50 pontos priorit\u00e1rios at\u00e9 o final de 2012. Caber\u00e3o as subprefeituras a tarefa de articular com os diversos parceiros locais: representantes das comunidades; Corpo de Bombeiros; Sabesp; AES Eletropaulo, a implementa\u00e7\u00e3o do plano de prev\u00ea entre outras a\u00e7\u00f5es: alargamento de ruas, retirada de <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-467","post","type-post","status-publish","format-standard","hentry","category-noticias-itaquera"],"_links":{"self":[{"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/posts\/467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=467"}],"version-history":[{"count":1,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/posts\/467\/revisions"}],"predecessor-version":[{"id":10741,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/posts\/467\/revisions\/10741"}],"wp:attachment":[{"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}