{"id":8917,"date":"2014-01-15T10:29:45","date_gmt":"2014-01-15T12:29:45","guid":{"rendered":"http:\/\/www.encontraitaquera.com.br\/noticias\/?p=8917"},"modified":"2019-04-12T18:45:15","modified_gmt":"2019-04-12T20:45:15","slug":"sesc-itaquera-recebe-a-trupe-irmao-atada","status":"publish","type":"post","link":"https:\/\/www.encontraitaquera.com.br\/sobre\/sesc-itaquera-recebe-a-trupe-irmao-atada\/","title":{"rendered":"SESC Itaquera recebe a Trupe Irm\u00e3o Atada"},"content":{"rendered":"<div class=\"f6a401da1b960306e8d5ff784b0b5528\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Como seria um espet\u00e1culo circense realizado apenas por palha\u00e7os? Uma trapalhada s\u00f3!!!\u00a0 No espet\u00e1culo \u201cTr\u00eas Variando\u201d, o p\u00fablico \u00e9 recepcionado pelo Palha\u00e7o Sandoval, que d\u00e1 as boas vindas aos que entram no grande Circo Irm\u00e3os Atada.<\/p>\n<p>No picadeiro, o p\u00fablico poder\u00e1 se divertir com as palha\u00e7adas e os diversos n\u00fameros de variedades do circo cl\u00e1ssico e contempor\u00e2neo. Sob o comando do Palha\u00e7o Granado, um m\u00e1gico atrapalhado e dono do circo, os tr\u00eas palha\u00e7os da Trupe Irm\u00e3o Atada demonstram suas habilidades em n\u00fameros de malabares de chap\u00e9u, prato chin\u00eas, equil\u00edbrio, telepatia, chicote, karat\u00ea e dan\u00e7a, sempre regados com grandes doses de gra\u00e7a do come\u00e7o ao fim, desde a montagem da lona at\u00e9 o apagar das \u00faltimas luzes.<\/p>\n<p><strong>Sobre a Trupe Irm\u00e3os Atada<\/strong><\/p>\n<p>Formada pelo artistas Anderson Spada, Emerson Almeida, Paulo Ygar e Sandro Fontes, a Trupe Irm\u00e3os Atada surgiu em 2010, e dedica-se \u00e0 pesquisa e treinamento da linguagem c\u00f4mica. Seu trabalho mais recente, \u201cBang Bang \u00e0 Pastelana\u201d \u00e9 bastante conhecido, e um sucesso por onde passa.<\/p>\n<p>Os artistas t\u00eam hist\u00f3ria juntos, tamb\u00e9m trabalharam, no Grupo Galp\u00e3o do Cl\u00e3, onde mergulharam numa intensa pesquisa na m\u00e1scara do palha\u00e7o e montaram diversos espet\u00e1culos e esquetes, tais como: \u201cPanet et Circus\u201d, espet\u00e1culo resultado do Pr\u00eamio Funarte de Circo 2004; \u201cPano de Roda &#8211; Palha\u00e7os em Variedades\u201d resultado do Pr\u00eamio Funarte de Circo 2005; \u201cCirco de Roda\u201d e \u201cSanta Clowns\u201d, entre outros.<\/p>\n<p><b><span style=\"text-decoration: underline;\">Ficha T\u00e9cnica<\/span><\/b><\/p>\n<p><b>Dire\u00e7\u00e3o:<\/b> Anderson Spada<\/p>\n<p><b>Dramaturgia:<\/b> Trupe Irm\u00e3os Atada<\/p>\n<p><b>Elenco:<\/b> Emerson Almeida, Gabriel Granado, Paulo Ygar e Sandro Fontes<\/p>\n<p><b>Dire\u00e7\u00e3o Musical:<\/b> C\u00e9lio Collela<\/p>\n<p><b>Figurinos e Adere\u00e7os :<\/b> Denise Guilherme<\/p>\n<p><b>Ilumina\u00e7\u00e3o:<\/b> Cic Morais<\/p>\n<p><b>Cen\u00e1rio:<\/b> Anderson Spada<\/p>\n<p><b>Cenot\u00e9cnico:<\/b> Bira Nogueira<\/p>\n<p><b>Operador som e Luz:<\/b> Cic Morais<\/p>\n<p><b>Produ\u00e7\u00e3o Geral:<\/b> Trupe Irm\u00e3os Atada<\/p>\n<p><b>Assessoria de Imprensa:<\/b> Moretti Cultura e Comunica\u00e7\u00e3o<\/p>\n<p><b><span style=\"text-decoration: underline;\">SERVI\u00c7O:<\/span><\/b><\/p>\n<p><b>Onde: <\/b><a title=\"Sesc Itaquera\" href=\"http:\/\/www.encontraitaquera.com.br\/noticias\/sesc-itaquera.shtml\" target=\"_blank\">SESC Itaquera<\/a><\/p>\n<p><b>Quando: <\/b>Dia 17 de janeiro, sexta, 13h<\/p>\n<p><b>Endere\u00e7o:<\/b> Avenida Fernando do Esp\u00edrito Santo Alves de Matos, 1000 &#8211; Itaquera, S\u00e3o Paulo<br \/>\n<b>Informa\u00e7\u00f5es:<\/b> 11 2523-9200<\/p>\n<p><b>Quanto:<\/b> Gr\u00e1tis<\/p>\n<p><strong>Dura\u00e7\u00e3o:<\/strong> 50 minutos | livre<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Como seria um espet\u00e1culo circense realizado apenas por palha\u00e7os? Uma trapalhada s\u00f3!!!\u00a0 No espet\u00e1culo \u201cTr\u00eas Variando\u201d, o p\u00fablico \u00e9 recepcionado pelo Palha\u00e7o Sandoval, que d\u00e1 as boas vindas aos que entram no grande Circo Irm\u00e3os Atada. No picadeiro, o p\u00fablico poder\u00e1 se divertir com as palha\u00e7adas e os diversos n\u00fameros de variedades do circo cl\u00e1ssico e contempor\u00e2neo. Sob o comando do Palha\u00e7o Granado, um m\u00e1gico atrapalhado e dono do circo, os tr\u00eas palha\u00e7os da Trupe Irm\u00e3o Atada demonstram suas habilidades em n\u00fameros de malabares de chap\u00e9u, prato chin\u00eas, equil\u00edbrio, telepatia, chicote, karat\u00ea e dan\u00e7a, sempre regados com grandes doses de <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-8917","post","type-post","status-publish","format-standard","hentry","category-noticias-itaquera"],"_links":{"self":[{"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/posts\/8917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=8917"}],"version-history":[{"count":1,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/posts\/8917\/revisions"}],"predecessor-version":[{"id":10104,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/posts\/8917\/revisions\/10104"}],"wp:attachment":[{"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=8917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=8917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontraitaquera.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=8917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}